{"id":15530,"date":"2022-10-17T04:01:29","date_gmt":"2022-10-17T02:01:29","guid":{"rendered":"https:\/\/haitianinter.com\/2022\/10\/17\/die-herausforderung-annehmen\/"},"modified":"2024-11-30T00:03:47","modified_gmt":"2024-11-29T23:03:47","slug":"die-herausforderung-annehmen","status":"publish","type":"post","link":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/","title":{"rendered":"Die Herausforderung annehmen"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4>Hardcoat Technologies setzt \u201eTechnologie auf den Punkt\u201c erfolgreich f\u00fcr anspruchsvolle Aufgaben im Bereich der Fahrzeugbeleuchtung ein.<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-71823\" src=\"https:\/\/newsroom.haitian.com\/wp-content\/uploads\/sites\/4\/2023\/12\/Hardcoat_5.jpg\" alt=\"\" width=\"300\" height=\"96\" \/><\/p>\n<p>CEO und Pr\u00e4sident Nick Steffens ge- gr\u00fcndet und ist ein Tier-2-Zulieferer von Beleuchtungskomponenten f\u00fcr die Automo- bilindustrie mit Sitz in Knoxville, Tennessee, USA. Das Unternehmen hat sich auf den an- spruchsvollen Prozess des Spritzgie\u00dfens von Polycarbonat-Linsen f\u00fcr Scheinwerfer, Fern- und Nebelscheinwerfer spezialisiert, die f\u00fcr Witterungsbest\u00e4ndigkeit und Kratzfestigkeit thermisch hartbeschichtet werden. Zu den Produkten von Hardcoat Tech geh\u00f6ren auch Light Pipes und Carrier f\u00fcr die Automobilindus- trie. Zu den Kunden im Automobil-, ATV- und Industriemarkt geh\u00f6ren SL Tennessee, Truck- Lite, Rebo Lighting and Electronics und Hicks Plastics\/Myotech.<\/p>\n<p>Die Produkte des Verarbeiters finden sich in Fahr- zeugen wie dem GMC Sierra Truck, dem Ram Truck, dem Buick Enclave SUV, der Chevrolet Malibu Li- mousine und dem Ford F-150 Truck. In seiner Gr\u00fcn- dungsphase wuchs das Unternehmen von 2017 bis 2019 um 300 Prozent und von 2019 bis 2022 um weitere 200 Prozent. Das Wachstum des Unterneh- mens f\u00fchrte zu einem 2.183 Quadratmeter gro\u00dfen Anbau, der 2022 neben der urspr\u00fcnglichen Anlage er\u00f6ffnet wurde. Bis 2022 hat Hardcoat Technologies 10 Spritzgie\u00dfmaschinen von Absolute Haitian, dem exklusiven Vertriebspartner f\u00fcr Haitian International in den USA und Kanada, erworben. Der Maschinen- park besteht aus servo-hydraulischen Mars-Serien \u2013 die \u201eArbeitspferde\u201c des Unternehmens \u2013 sowie eine servo-hydraulische Zwei-Platten-Maschine Ju- piter und zwei elektrische Zeres Maschinen. \u201eWir spezifizieren unsere Maschinen immer mit kleineren Einspritzeinheiten, um den besonderen Eigenschaf- ten unserer Werkzeuge Rechnung zu tragen und die Verweilzeit des Materials im Zylinder zu verk\u00fcrzen\u201d, so Steffens.<\/p>\n<p>\u201eAutomobilscheinwerfer m\u00fcssen eine hohe Schlag- festigkeit, Witterungsbest\u00e4ndigkeit und Kratzfes- tigkeit aufweisen. Viele prophezeiten uns, es w\u00e4re nahezu unm\u00f6glich hochwertige Polycarbonat-Gl\u00e4ser auf \u201eStandardmaschinen\u201c herzustellen. Wir arbei- ten seit 25 Jahren mit dem Werkstoff Polycarbonat\u201d, sagt Steffens. \u201cMit robusten Prozessen, zuverl\u00e4ssi- gen Spritzgussmaschinen und einem konsequen- ten Wartungsprogramm schaffen erreichen wir eine Ausschussraten von weniger als 2 %.\u201d<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/haitianinter.com\/wp-content\/uploads\/sites\/4\/2022\/10\/Hardcoat_2.jpg&#8220; title_text=&#8220;Hardcoat 2&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/haitianinter.com\/wp-content\/uploads\/sites\/4\/2022\/10\/Hardcoat_3.jpg&#8220; title_text=&#8220;Hardcoat 3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/haitianinter.com\/wp-content\/uploads\/sites\/4\/2022\/10\/Hardcoat_4.jpg&#8220; title_text=&#8220;Hardcoat 4&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Das Unternehmen verarbeitet auch Acryl- und PC- Material auf einer Zhafir Zeres mit 4500 kN Schlie\u00df- kraft und, ausgestattet mit einer Spezial-Schnecke zur Herstellung von Lichtleitern f\u00fcr LED-Beleuchtung in High-End-Fahrzeugen. \u201eDas Preisniveau der Ma- schinen von Zhafir und Haitian macht Haitian Inter- national als Lieferant sehr attraktiv\u201d, so Steffens. \u201eWir sind in der Lage, unseren Kunden die neueste Tech- nologie f\u00fcr thermisch aush\u00e4rtende Silikon-Hardco- ats anzubieten und gleichzeitig unsere Preise f\u00fcr sie wettbewerbsf\u00e4hig zu halten.\u201d<\/p>\n<p>Hardcoat Technologies stellt ihr Hardcoating-Equip- ment und -Werkzeuge selbst her. Sie investierten auch in einen 1500-Laser f\u00fcr die Fertigung und 3D- Drucker f\u00fcr die Herstellung von Prototypen, womit sie anstelle der \u00fcblichen 2 bis 6 Wochen Prototypen innerhalb von Stunden fertigstellen k\u00f6nnen.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;2_5,3_5&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#8ec5f9&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/haitianinter.com\/wp-content\/uploads\/sites\/4\/2022\/10\/Hardcoat_6.jpg&#8220; title_text=&#8220;Hardcoat 6&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h3><span style=\"font-size: 14pt\"><em>Durch den Standort Knoxville ist Hardcoat Technolo- gies in der Lage, mit Automobilzulieferern im S\u00fcden der USA zusammenzuarbeiten. \u201eMit Tier-1-Zulie- ferern von GM und Nissan in Tennessee, BMW in South Carolina, Mercedes und KIA\/Hyundai in Geor- gia und Alabama sind wir in einer guten Position, um unser Wachstum fortzusetzen\u201d, so Steffens.<\/em><\/span><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Die Automobilindustrie ist ein schwer zu er- schlie\u00dfender Markt, aber Steffens verf\u00fcgte \u00fcber Beziehungen, die er in mehr als 17 Jahren als Ver- antwortlicher f\u00fcr die kommerzielle Entwicklung aufgebaut hatte, bevor er Hardcoat Technologies gr\u00fcndete. \u201eUnser Ziel ist es, Teile schnell herzustel- len und unseren Kunden einen Mehrwert zu bieten. Wir bringen Erfahrung und technisches Know-how mit. Haitian International bringt das Know-How \u00fcber die Herstellung von zuverl\u00e4ssigen Spritzgie\u00dfmaschi- nen mit und das Team von Absolute Haitian liefert den von uns geforderten Vertrieb und Service mit einer vorbildlichen Ersatzteilverf\u00fcgbarkeit. Dies war der Weg, der unser Unternehmen zum Erfolg ge- f\u00fchrt hat\u201d, so Steffens abschlie\u00dfend.<\/p>\n<h4>Zahlen &amp; Fakten:<\/h4>\n<p>Gegr\u00fcndet: 2014<br \/>ISO 9001-zertifiziert<br \/>Reinraum-Beschichtungsumgebung f\u00fcr das selbst entwickelte Hardcoat-Verfahren<br \/>10+2 injection molding machines:<br \/>ZE 3600\/1400, ZE 4500\/1400, JU III 4500\/1730, MA II 3200\/1700, MA II 5300\/4500, MA II 6000\/4500, MA III 3800\/1700, MA III 3800\/1700, MA III 6000\/2250, \u00a0MA III 6000\/2250<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;] Hardcoat Technologies setzt \u201eTechnologie auf den Punkt\u201c erfolgreich f\u00fcr anspruchsvolle Aufgaben im Bereich der Fahrzeugbeleuchtung ein. CEO und Pr\u00e4sident Nick Steffens ge- gr\u00fcndet und ist ein Tier-2-Zulieferer von Beleuchtungskomponenten f\u00fcr die Automo- bilindustrie mit Sitz in Knoxville, Tennessee, USA. Das [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":9456,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-15530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Herausforderung annehmen - Haitian International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Herausforderung annehmen - Haitian International\" \/>\n<meta property=\"og:description\" content=\"[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;] Hardcoat Technologies setzt \u201eTechnologie auf den Punkt\u201c erfolgreich f\u00fcr anspruchsvolle Aufgaben im Bereich der Fahrzeugbeleuchtung ein. CEO und Pr\u00e4sident Nick Steffens ge- gr\u00fcndet und ist ein Tier-2-Zulieferer von Beleuchtungskomponenten f\u00fcr die Automo- bilindustrie mit Sitz in Knoxville, Tennessee, USA. Das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/\" \/>\n<meta property=\"og:site_name\" content=\"Haitian International\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-17T02:01:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-29T23:03:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsroom.haitian.com\/wp-content\/uploads\/sites\/4\/2023\/12\/Hardcoat_5.jpg\" \/>\n<meta name=\"author\" content=\"haitianwiesnerd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"haitianwiesnerd\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/\"},\"author\":{\"name\":\"haitianwiesnerd\",\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/#\\\/schema\\\/person\\\/6aee888a065f2f55aef76248e9d276ea\"},\"headline\":\"Die Herausforderung annehmen\",\"datePublished\":\"2022-10-17T02:01:29+00:00\",\"dateModified\":\"2024-11-29T23:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/\"},\"wordCount\":1022,\"image\":{\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/haitianinter.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/Hardcoat_1.jpg\",\"articleSection\":[\"All\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/\",\"url\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/\",\"name\":\"Die Herausforderung annehmen - Haitian International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/haitianinter.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/Hardcoat_1.jpg\",\"datePublished\":\"2022-10-17T02:01:29+00:00\",\"dateModified\":\"2024-11-29T23:03:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/#\\\/schema\\\/person\\\/6aee888a065f2f55aef76248e9d276ea\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/haitianinter.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/Hardcoat_1.jpg\",\"contentUrl\":\"https:\\\/\\\/haitianinter.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/Hardcoat_1.jpg\",\"width\":1000,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/all-en\\\/die-herausforderung-annehmen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Herausforderung annehmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/\",\"name\":\"Haitian International\",\"description\":\"We Create and Extend Advantage\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/#\\\/schema\\\/person\\\/6aee888a065f2f55aef76248e9d276ea\",\"name\":\"haitianwiesnerd\",\"url\":\"https:\\\/\\\/haitianinter.com\\\/de\\\/author\\\/haitianwiesnerd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Herausforderung annehmen - Haitian International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/","og_locale":"de_DE","og_type":"article","og_title":"Die Herausforderung annehmen - Haitian International","og_description":"[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;] Hardcoat Technologies setzt \u201eTechnologie auf den Punkt\u201c erfolgreich f\u00fcr anspruchsvolle Aufgaben im Bereich der Fahrzeugbeleuchtung ein. CEO und Pr\u00e4sident Nick Steffens ge- gr\u00fcndet und ist ein Tier-2-Zulieferer von Beleuchtungskomponenten f\u00fcr die Automo- bilindustrie mit Sitz in Knoxville, Tennessee, USA. Das [&hellip;]","og_url":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/","og_site_name":"Haitian International","article_published_time":"2022-10-17T02:01:29+00:00","article_modified_time":"2024-11-29T23:03:47+00:00","og_image":[{"url":"https:\/\/newsroom.haitian.com\/wp-content\/uploads\/sites\/4\/2023\/12\/Hardcoat_5.jpg","type":"","width":"","height":""}],"author":"haitianwiesnerd","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"haitianwiesnerd","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/#article","isPartOf":{"@id":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/"},"author":{"name":"haitianwiesnerd","@id":"https:\/\/haitianinter.com\/de\/#\/schema\/person\/6aee888a065f2f55aef76248e9d276ea"},"headline":"Die Herausforderung annehmen","datePublished":"2022-10-17T02:01:29+00:00","dateModified":"2024-11-29T23:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/"},"wordCount":1022,"image":{"@id":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/#primaryimage"},"thumbnailUrl":"https:\/\/haitianinter.com\/wp-content\/uploads\/sites\/3\/2024\/10\/Hardcoat_1.jpg","articleSection":["All"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/","url":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/","name":"Die Herausforderung annehmen - Haitian International","isPartOf":{"@id":"https:\/\/haitianinter.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/#primaryimage"},"image":{"@id":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/#primaryimage"},"thumbnailUrl":"https:\/\/haitianinter.com\/wp-content\/uploads\/sites\/3\/2024\/10\/Hardcoat_1.jpg","datePublished":"2022-10-17T02:01:29+00:00","dateModified":"2024-11-29T23:03:47+00:00","author":{"@id":"https:\/\/haitianinter.com\/de\/#\/schema\/person\/6aee888a065f2f55aef76248e9d276ea"},"breadcrumb":{"@id":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/#primaryimage","url":"https:\/\/haitianinter.com\/wp-content\/uploads\/sites\/3\/2024\/10\/Hardcoat_1.jpg","contentUrl":"https:\/\/haitianinter.com\/wp-content\/uploads\/sites\/3\/2024\/10\/Hardcoat_1.jpg","width":1000,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/haitianinter.com\/de\/all-en\/die-herausforderung-annehmen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/haitianinter.com\/de\/"},{"@type":"ListItem","position":2,"name":"Die Herausforderung annehmen"}]},{"@type":"WebSite","@id":"https:\/\/haitianinter.com\/de\/#website","url":"https:\/\/haitianinter.com\/de\/","name":"Haitian International","description":"We Create and Extend Advantage","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/haitianinter.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/haitianinter.com\/de\/#\/schema\/person\/6aee888a065f2f55aef76248e9d276ea","name":"haitianwiesnerd","url":"https:\/\/haitianinter.com\/de\/author\/haitianwiesnerd\/"}]}},"_links":{"self":[{"href":"https:\/\/haitianinter.com\/de\/wp-json\/wp\/v2\/posts\/15530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/haitianinter.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/haitianinter.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/haitianinter.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/haitianinter.com\/de\/wp-json\/wp\/v2\/comments?post=15530"}],"version-history":[{"count":0,"href":"https:\/\/haitianinter.com\/de\/wp-json\/wp\/v2\/posts\/15530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/haitianinter.com\/de\/wp-json\/wp\/v2\/media\/9456"}],"wp:attachment":[{"href":"https:\/\/haitianinter.com\/de\/wp-json\/wp\/v2\/media?parent=15530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/haitianinter.com\/de\/wp-json\/wp\/v2\/categories?post=15530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/haitianinter.com\/de\/wp-json\/wp\/v2\/tags?post=15530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}